{"id":10019,"date":"2023-03-17T11:37:50","date_gmt":"2023-03-17T10:37:50","guid":{"rendered":"http:\/\/blog.rheinhessen.de\/?p=10019"},"modified":"2023-10-17T09:53:01","modified_gmt":"2023-10-17T07:53:01","slug":"ou-les-pierres-racontent-des-histoires","status":"publish","type":"post","link":"https:\/\/rheinhessenblog.de\/fr\/wo-steine-geschichten-erzaehlen\/","title":{"rendered":"O\u00f9 les pierres racontent une ou plusieurs histoires"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"423\" src=\"https:\/\/rh.laolaweb.com\/wp-content\/uploads\/2023\/03\/Aussen-1-scaled-e1679049277270-1024x423.jpg\" alt=\"\" class=\"wp-image-10100\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Aussen-1-scaled-e1679049277270-1024x423.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Aussen-1-scaled-e1679049277270-300x124.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Aussen-1-scaled-e1679049277270-768x317.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Aussen-1-scaled-e1679049277270-1536x635.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Aussen-1-scaled-e1679049277270-2048x846.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"> La nouvelle salle en pierre du mus\u00e9e d'Alzey fait revivre l'\u00e9poque romaine <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ils sont immobiles et muets. Et pourtant, ils racontent\nl'histoire et des histoires. Pendant longtemps, ils ont men\u00e9 une existence morne dans une\ndans l'arri\u00e8re-cour du Burggrafiat d'Alzey. Aux yeux de\ncach\u00e9s aux yeux du public. Mais aujourd'hui, les t\u00e9moignages du pass\u00e9\npass\u00e9 romain ont obtenu une grande sc\u00e8ne - et quelle sc\u00e8ne ! Dans la\nnouvelle salle en pierre du mus\u00e9e municipal d'Alzey, des pierres de temple, des chapiteaux, des colonnes\net d'autres objets datant du 1er au 3e si\u00e8cle apr\u00e8s J.-C. sont expos\u00e9s.\nsont pr\u00e9sent\u00e9s de mani\u00e8re spectaculaire. Un must pour les fans des Romains et les arch\u00e9ologues.\nmais aussi pour tous les autres visiteurs de la Hesse rh\u00e9nane.\n\u201ecapitale secr\u00e8te\u201c. Et ce, notamment en raison de l'architecture moderne et sacr\u00e9e de l'\u00e9difice.\nl'architecture de l'\u00e9difice. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"10059\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_7_CC_BY-Annegret-Hirschmann-1-scaled-1-683x1024.jpg\" alt=\"\" class=\"wp-image-10059\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_7_CC_BY-Annegret-Hirschmann-1-scaled-1-683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_7_CC_BY-Annegret-Hirschmann-1-scaled-1-200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_7_CC_BY-Annegret-Hirschmann-1-scaled-1-768x1152.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_7_CC_BY-Annegret-Hirschmann-1-scaled-1-1024x1536.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_7_CC_BY-Annegret-Hirschmann-1-scaled-1-1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_7_CC_BY-Annegret-Hirschmann-1-scaled-1.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\"> Avec sa forme moderne, le hall en pierre est un point d'exclamation optique dans le paysage urbain d'Alzey (c) Annegret Hirschmann<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10060\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_31_CC_BY-Annegret-Hirschmann-scaled-1-1024x683.jpg\" alt=\"\" class=\"wp-image-10060\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_31_CC_BY-Annegret-Hirschmann-scaled-1-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_31_CC_BY-Annegret-Hirschmann-scaled-1-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_31_CC_BY-Annegret-Hirschmann-scaled-1-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_31_CC_BY-Annegret-Hirschmann-scaled-1-1536x1024.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_31_CC_BY-Annegret-Hirschmann-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">De grandes fen\u00eatres sur les murs lat\u00e9raux laissent entrer beaucoup de lumi\u00e8re du jour. Ce sont des \u201evitrines\u201c au sens propre du terme. (c) Annegret Hirschmann<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10058\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_64_CC_BY-Annegret-Hirschmann-scaled-1-1024x683.jpg\" alt=\"\" class=\"wp-image-10058\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_64_CC_BY-Annegret-Hirschmann-scaled-1-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_64_CC_BY-Annegret-Hirschmann-scaled-1-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_64_CC_BY-Annegret-Hirschmann-scaled-1-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_64_CC_BY-Annegret-Hirschmann-scaled-1-1536x1024.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Steinhalle_64_CC_BY-Annegret-Hirschmann-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Bien mis en lumi\u00e8re par une technique d'\u00e9clairage sophistiqu\u00e9e : les tr\u00e9sors romains du mus\u00e9e d'Alzey (c) Annegret Hirschmann<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En entrant dans la salle de 30 m\u00e8tres de long\net d'une hauteur de six m\u00e8tres, le regard embrasse la phalange de sculptures.\ncolonnes, parall\u00e9l\u00e9pip\u00e8des et sculptures. Celles-ci sont d'une part \u00e9clair\u00e9es par une ing\u00e9nieuse\nd'\u00e9clairage, et d'autre part, les grandes baies vitr\u00e9es qui\nrectangulaires sur les murs lat\u00e9raux, la lumi\u00e8re du jour p\u00e9n\u00e8tre. Ce sont des \u201evitrines\u201c.\nau sens propre du terme, comme l'explique le directeur du mus\u00e9e, Dr. Rainer Karneth\nCes grandes fen\u00eatres doivent \u00e9veiller la curiosit\u00e9 des gens.\nde ce que nous avons ici\u201e. C'est particuli\u00e8rement impressionnant apr\u00e8s\n\u00e0 la tomb\u00e9e de la nuit, lorsque l'int\u00e9rieur est illumin\u00e9 et la fa\u00e7ade\nest illumin\u00e9e. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'ensemble du corps de b\u00e2timent est alors encore plus\nplus impressionnant que pendant la journ\u00e9e. Le b\u00e2timent, recouvert de panneaux en terre cuite gris-brun, contraste avec le\ncontraste avec le b\u00e2timent baroque du mus\u00e9e, qui abritait autrefois un h\u00f4pital.\nh\u00f4pital qui y \u00e9tait install\u00e9. Un contraste que l'architecte Ernst Eichler a d\u00e9lib\u00e9r\u00e9ment choisi.\na \u00e9t\u00e9 d\u00e9lib\u00e9r\u00e9ment mis en place. \u201eC'est un mus\u00e9e et il doit \u00eatre reconnaissable en tant que tel.\n\u00eatre\u201c, explique l'architecte d'Alzey. Une copie stylistique du mus\u00e9e existant, auquel il \u00e9tait annex\u00e9, n'\u00e9tait pas envisageable.\nauquel le hall en pierre a \u00e9t\u00e9 ajout\u00e9, \u00e9tait d'embl\u00e9e interdit pour Eichler. \u201eNous avons\nnous voulions cr\u00e9er un contraste saisissant avec l'ancienne maison et un dialogue qui\nles deux styles\u201c, explique Eichler. Les constructions environnantes sont caract\u00e9ris\u00e9es par\nun m\u00e9lange de styles agit\u00e9 des ann\u00e9es soixante et soixante-dix. Dans ce sens, il serait\nune architecture historiciste \u00e0 cet endroit n'est pas non plus une solution concluante.\nAvec sa forme moderne, le hall en pierre constitue un point de rep\u00e8re dans l'architecture de l'immeuble.\npoint d'exclamation optique dans le paysage urbain d'Alzey. Une optique qui impressionne - et qui polarise.\net qui polarise. Mais l'esth\u00e9tique de cette construction d\u00e9pend aussi de l'\u0153il de l'utilisateur.\nde l'observateur. Les moqueurs reprochent \u00e0 la construction de faire penser \u00e0 un sous-marin. Cela ne les d\u00e9range pas.\nMais le directeur du mus\u00e9e Karneth s'en accommode bien. \u201eNous nous plongeons dans l'histoire de la ville.\nhistoire romaine dans notre ville\u201c, fait-il remarquer avec un clin d'\u0153il.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les co\u00fbts de construction s'\u00e9l\u00e8vent \u00e0 3,3 millions d'euros.\nco\u00fbts de construction. Ce n'est pas une mince affaire. Mais cette somme comprend \u00e9galement l'am\u00e9nagement\nl'acc\u00e8s sans obstacle au parking souterrain de la ville et le raccordement au mus\u00e9e.\nsont inclus. 85 % des co\u00fbts de la Steinhalle sont financ\u00e9s par l'Union europ\u00e9enne.\nUnion europ\u00e9enne. Sans ces fonds affect\u00e9s, ce b\u00e2timent culturel n'aurait pas pu \u00eatre r\u00e9alis\u00e9.\nn'aurait pas pu \u00eatre r\u00e9alis\u00e9. Si les habitants d'Alzey n'avaient pas saisi l'occasion\nles fonds auraient \u00e9t\u00e9 allou\u00e9s \u00e0 une autre ville ou r\u00e9gion.\nau sein de l'UE. Les pierres romaines seraient alors rest\u00e9es en place jusqu'au\nElles auraient alors disparu dans l'arri\u00e8re-cour du Burggrafiat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la construction, seuls des mat\u00e9riaux\nque les Romains connaissaient d\u00e9j\u00e0 : Bois, verre, argile et b\u00e9ton. Du b\u00e9ton ? Oui, c'est vrai,\nDu b\u00e9ton. \u201eLes Romains l'avaient \u201ainvent\u00e9\u2018\u201c, explique Eichler. Et c'est ainsi que\nle b\u00e2timent jette un pont vers son contenu. Celui-ci offre \u00e0 l'observateur des\nun aper\u00e7u \u00e0 la fois profond et surprenant de l'\u00e9poque d'il y a environ 2000 ans.\nans, quand Alzey s'appelait encore Altiaium. Ce nom est mentionn\u00e9 pour la premi\u00e8re fois sur une\nune pierre de nymphe datant de 223 apr\u00e8s J.-C.. Celle-ci est expos\u00e9e dans la bien\nsection romaine du mus\u00e9e d'\u00e0 c\u00f4t\u00e9. Cet \u201eacte de naissance\u201c fait de\nAlzey l'une des plus anciennes villes d'Allemagne. Ainsi, Alzey est mentionn\u00e9e d\u00e8s le 18e si\u00e8cle.\nsi\u00e8cle, lorsque l'autel des nymphes a \u00e9t\u00e9 trouv\u00e9, comme une ancienne ville romaine.\nd\u00e9crite.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"10061\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Nymphenstein--683x1024.jpg\" alt=\"\" class=\"wp-image-10061\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Nymphenstein--683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Nymphenstein--200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Nymphenstein--768x1151.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Nymphenstein--1025x1536.jpg 1025w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Nymphenstein--1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Nymphenstein-.jpg 1441w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">Pierre des nymphes : le nom d'Alzey est mentionn\u00e9 pour la premi\u00e8re fois sur l'autel des nymphes datant de 223 apr\u00e8s J.-C., d\u00e9couvert en 1783. Il est ainsi consid\u00e9r\u00e9 comme \u201el'acte de naissance\u201c de la ville. <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les fouilles men\u00e9es dans les ann\u00e9es\nmises au jour en 1929\/31 corroborent cet attribut. Environ 80 autels ont \u00e9t\u00e9 d\u00e9couverts,\npierres de cons\u00e9cration, des morceaux de colonnes de Jupiter et des fragments d'architecture datant du\nentre le 1er et le 3e si\u00e8cle apr\u00e8s J.-C. ont \u00e9t\u00e9 d\u00e9couverts \u00e0 l'\u00e9poque non loin de l'ancien site arch\u00e9ologique.\nl'emplacement de l'ancien fort romain. Ils proviennent du\nVicus Altiaium et \u00e9taient plus tard install\u00e9s dans un b\u00e2timent du fort. Les\nconstructeurs et artisans romains utilisaient alors du gr\u00e8s clair\ndes carri\u00e8res de Flonheim situ\u00e9es \u00e0 proximit\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e8s de huit d\u00e9cennies plus tard, en 2003, une autre d\u00e9couverte spectaculaire a plac\u00e9 une fois de plus Alzey sous le feu des projecteurs des sp\u00e9cialistes. Avec un autel Magna Mater et des parties d'un pilier des dieux, d'autres t\u00e9moignages importants de l'histoire de la ville romaine ont \u00e9t\u00e9 mis au jour. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"10062\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Magna-MaterAltar--683x1024.jpg\" alt=\"\" class=\"wp-image-10062\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Magna-MaterAltar--683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Magna-MaterAltar--200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Magna-MaterAltar--768x1151.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Magna-MaterAltar--1025x1536.jpg 1025w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Magna-MaterAltar--1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Magna-MaterAltar-.jpg 1441w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">Autel Magna Mater : le 11 novembre 237 apr\u00e8s J.-C., Pacatia Pacata, fille d'un conseiller de Tr\u00e8ves, fit don d'un autel \u00e0 la Grande D\u00e9esse M\u00e8re, \u00e9galement appel\u00e9e Cyb\u00e8le. Les Romains adopt\u00e8rent ce culte originaire d'Asie mineure en 204 av. J.-C. La pierre de l'autel \u00e9tait d\u00e9di\u00e9e au pouvoir de procr\u00e9ation de Patricius Cybelicus, qui s'\u00e9tait \u00e9mascul\u00e9 pour la Grande M\u00e8re des dieux. <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eAlzey a ainsi acquis une grande\ndans le monde de l'arch\u00e9ologie romaine\u201c, explique Rainer Karneze.\nKarneth l'importance de ces d\u00e9couvertes. \u201eLa d\u00e9couverte de 1929\/31 est l'une des plus importantes.\nplus grande sur le sol allemand\u201c. Dans un premier temps, les pierres romaines ont \u00e9t\u00e9 d\u00e9couvertes dans un b\u00e2timent de stockage\nde l'ancien complexe Prince Emil. Ensuite, elles ont migr\u00e9 dans le\nb\u00e2timent du casino, qui abrite aujourd'hui le centre culturel et de la jeunesse, avant d'\u00eatre\nElles ont ensuite disparu dans l'arri\u00e8re-cour d\u00e9j\u00e0 mentionn\u00e9e. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maintenant, les\npierres ont trouv\u00e9 un domicile o\u00f9 elles peuvent raconter leur histoire. Une\nUne histoire avec des chapitres remarquables. Par exemple, la d\u00e9couverte qu'Alzey \u00e9tait une ville thermale \u00e0 l'\u00e9poque\nl'\u00e9poque romaine, une station thermale et de cure\n\u00e9tait une ville thermale. L'activit\u00e9 thermale florissante de l'\u00e9poque reposait sur des sources et des bains thermaux.\nfontaines d'eau thermale sulfureuse. Cette eau \u00e9tait utilis\u00e9e dans les \u00e9tablissements thermaux par les\npersonnel m\u00e9dical aupr\u00e8s des curistes. Il y avait \u00e9galement un\ntemple o\u00f9 l'on pouvait se faire assister par les divinit\u00e9s des sources et de la gu\u00e9rison.\npouvait \u00eatre assur\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10071\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Apollo-Grannus-scaled-2-1024x683.jpg\" alt=\"\" class=\"wp-image-10071\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Apollo-Grannus-scaled-2-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Apollo-Grannus-scaled-2-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Apollo-Grannus-scaled-2-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Apollo-Grannus-scaled-2-1536x1025.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Apollo-Grannus-scaled-2-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Apollo Grannus : \u00e0 l'origine, inscription scell\u00e9e pour un sanctuaire d\u00e9di\u00e9 \u00e0 l'Apollon romain-celtique Grannus. Apollon, dieu romain des arts et de la gu\u00e9rison, \u00e9tait ici assimil\u00e9 au dieu celte Grannus, qui \u00e9tait v\u00e9n\u00e9r\u00e9 pr\u00e8s des sources curatives et invoqu\u00e9 en cas de maladie. La traduction de l'inscription est la suivante : C'est \u00e0 Apollon Grannus que Martius Senopatius a consacr\u00e9 (ce temple) le 18 ao\u00fbt sous les consuls Piso et Iulianius (175 apr\u00e8s J.-C.). <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les hommes de l'\u00e9poque aimaient recevoir cette aide des dieux.\nUne pierre de cons\u00e9cration datant de 175 apr\u00e8s J.-C. prouve que cette pierre faisait partie d'une\nprobablement partie int\u00e9grante d'un grand temple construit par Martius Senopatius Novellus\net d\u00e9di\u00e9 \u00e0 Apollon Grannus. C'est ce qui ressort de l'inscription. Apparemment\nla divinit\u00e9 romaine-celtique a particuli\u00e8rement aid\u00e9 Novellus \u00e0 se r\u00e9tablir.\na aid\u00e9 \u00e0 la gu\u00e9rison. En remerciement, ce dernier a fait \u00e9riger le temple. Mais l'aide \u00e9tait aussi apport\u00e9e par\nla d\u00e9esse de la gu\u00e9rison Sirona, qui, dans les provinces celtes, \u00e9tait consid\u00e9r\u00e9e comme\naccompagnant Apollo Grannus dans son culte. Les habitants de\nAlzey, ainsi qu'\u00e0 Junon et \u00e0 la d\u00e9esse de l'eau de la ville d'Alzey.\nDea Sulis, connue \u00e0 Bath en Angleterre, pour les nymphes et Apollo Demioncus.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10063\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-3a-1-scaled-1-1024x683.jpg\" alt=\"\" class=\"wp-image-10063\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-3a-1-scaled-1-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-3a-1-scaled-1-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-3a-1-scaled-1-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-3a-1-scaled-1-1536x1025.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-3a-1-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Des colonnes de Jupiter : Dans la salle en pierre du mus\u00e9e d'Alzey, on peut voir plusieurs colonnes de Jupiter ou des parties isol\u00e9es de ces colonnes, qui \u00e9taient d\u00e9di\u00e9es au dieu supr\u00eame des Romains.<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Une partie non n\u00e9gligeable des pierres expos\u00e9es sont des parties de\ncolonnes de Jupiter. Les repr\u00e9sentations du dieu romain sont particuli\u00e8rement attrayantes.\nprincipal dieu en tant que cavalier g\u00e9ant. Barbu et avec une chevelure ondoyante\nJupiter chevauche un g\u00e9ant \u00e0 terre. Le vaincu\nennemi des dieux est repr\u00e9sent\u00e9 dans la sculpture du 3e si\u00e8cle ap.\n\u00eatre hybride avec un corps humain et des jambes de serpent. Ce n'est pas seulement sur la\ncette sculpture, le regard reste accroch\u00e9 et, en y regardant de plus pr\u00e8s, on d\u00e9couvre des\ndes d\u00e9tails charmants. On s'\u00e9tonne et on se voit soudain plong\u00e9 dans l'histoire de l'humanit\u00e9.\nla mythologie romaine et ses dieux.\net les rituels.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10065\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1-1024x683.jpg\" alt=\"\" class=\"wp-image-10065\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1-1536x1025.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Colonne de Jupiter G\u00e9ants : Cette partie sup\u00e9rieure d'une colonne de Jupiter du 3e si\u00e8cle montre Jupiter, le dieu romain de l'\u00c9tat et du ciel, chevauchant un g\u00e9ant couch\u00e9 au sol.<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"10080\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Viergoetterstein-1-683x1024.jpg\" alt=\"\" class=\"wp-image-10080\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Viergoetterstein-1-683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Viergoetterstein-1-200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Viergoetterstein-1-768x1151.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Viergoetterstein-1-1025x1536.jpg 1025w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Viergoetterstein-1-1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Viergoetterstein-1.jpg 1441w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">Pierre des quatre dieux : les dieux romains Vulcain, V\u00e9nus, Minerve et Hercule sont repr\u00e9sent\u00e9s sur cette pierre des quatre dieux d'une colonne de Jupiter datant du 1er si\u00e8cle apr\u00e8s J\u00e9sus-Christ.<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eCe qui est important pour nous aujourd'hui, c'est l'\u00e9ventail des dieux.\nLes dieux qui sont repr\u00e9sent\u00e9s ici\u201c, explique le directeur du mus\u00e9e Karneth.\nles connaissances pour la post\u00e9rit\u00e9 que l'on peut lire dans les pierres. De m\u00eame\nque les d\u00e9couvertes qui y sont expos\u00e9es, la salle des pierres rencontre un \u00e9cho favorable aupr\u00e8s des sp\u00e9cialistes.\nun \u00e9cho prometteur. Ainsi, la Direction g\u00e9n\u00e9rale des affaires culturelles\nPatrimoine de Rh\u00e9nanie-Palatinat est favorable au projet. La Steinhalle devrait en outre\nfaire partie de la route romaine de la Hesse rh\u00e9nane (<a href=\"http:\/\/www.roemerroute-rheinhessen.de\">www.roemerroute-rheinhessen.de<\/a>)\nsera une \u00e9tape importante. \u201eAlzey sera l'un des jalons de cet itin\u00e9raire\u201c, assure Rainer Karneth.\nKarneth en est certain. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La collection d'objets romains pr\u00e9sent\u00e9e dans la salle des pierres\nest pr\u00e9sent\u00e9e aux visiteurs de mani\u00e8re informative. Des panneaux de texte donnent des\ndonnent des informations sur l'objet en question. Un code QR permet \u00e9galement au visiteur d'acc\u00e9der \u00e0 des\nacc\u00e9der \u00e0 des sources d'information num\u00e9riques. Des panneaux de texte plus grands sur les murs\nfournissent des informations de fond concises sur l'\u00e9poque romaine \u00e0 Alzey et\nIls aident les visiteurs \u00e0 classer ce qu'ils ont vu. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10072\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-1-scaled-1-1024x683.jpg\" alt=\"\" class=\"wp-image-10072\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-1-scaled-1-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-1-scaled-1-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-1-scaled-1-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-1-scaled-1-1536x1025.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-1-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Multim\u00e9dia 1 et 2 : une station multim\u00e9dia est install\u00e9e sur une plateforme \u00e0 l'\u00e9tage sup\u00e9rieur du hall en pierre, o\u00f9 l'on peut se plonger virtuellement et de mani\u00e8re interactive dans le monde des Romains. De l\u00e0, on a \u00e9galement une bonne vue d'ensemble de la salle d'exposition. <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-11 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"10073\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-3--683x1024.jpg\" alt=\"\" class=\"wp-image-10073\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-3--683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-3--200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-3--768x1151.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-3--1025x1536.jpg 1025w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-3--1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Multimedia-3-.jpg 1441w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sur une plate-forme \u00e0 l'\u00e9tage sup\u00e9rieur du hall de pierre\nune station multim\u00e9dia est install\u00e9e, o\u00f9 l'on peut, gr\u00e2ce \u00e0 deux \u00e9crans d'ordinateur\non peut se plonger virtuellement et de mani\u00e8re interactive dans le monde des Romains. De l\u00e0, on a une vue d'ensemble\n\u00e9galement une bonne vue d'ensemble de la salle d'exposition. L'\u00e9quipement de cette derni\u00e8re comprendra\n\u00e0 l'avenir, un d\u00e9tail multim\u00e9dia particulier : Une \u201edouche sonore\u201c dans l'entr\u00e9e.\ndans la zone d'entr\u00e9e. En se pla\u00e7ant en dessous, on d\u00e9couvre des informations int\u00e9ressantes sur l'histoire d'Alzey.\nl'histoire de la ville. Ce texte, diffus\u00e9 en boucle, a \u00e9t\u00e9 prononc\u00e9 par l'artiste de la ville.\npar l'acteur de Mayence Tino Leo. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-12 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10074\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Museum-3-scaled-2-1024x683.jpg\" alt=\"\" class=\"wp-image-10074\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Museum-3-scaled-2-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Museum-3-scaled-2-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Museum-3-scaled-2-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Museum-3-scaled-2-1536x1025.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Museum-3-scaled-2-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Dans le mus\u00e9e municipal voisin d'Alzey, de nombreuses d\u00e9couvertes de l'\u00e9poque romaine sont expos\u00e9es dans des vitrines. <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Avec la nouvelle Steinhalle, la ville de Volker a gagn\u00e9 une\na gagn\u00e9 une attraction qui rayonne au-del\u00e0 des fronti\u00e8res de la ville. L'exposition\ndonne un aper\u00e7u de l'\u00e9poque o\u00f9 les Romains dominaient la r\u00e9gion avec leur culture.\nSi vous souhaitez en savoir plus sur les autres \u00e9poques de l'histoire de la ville, visitez le mus\u00e9e de la pierre.\ndevrait absolument visiter le mus\u00e9e de la ville, reli\u00e9 \u00e0 la Steinhalle. Son site\npr\u00e9sente \u00e9galement de mani\u00e8re claire un aper\u00e7u de l'histoire de la ville.\nl'histoire mouvement\u00e9e d'Alzey. Convivial pour l'utilisateur. En effet, comme la Steinhalle elle-m\u00eame, le mus\u00e9e est\nle mus\u00e9e est \u00e9galement accessible gratuitement aux personnes \u00e0 mobilit\u00e9 r\u00e9duite. Une offre qui ne manque pas de sel,\nqui n'existe pas partout. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salle en pierre et mus\u00e9e de la ville d'Alzey<br>\n41, rue des Antonites<br>\n55232 Alzey<br>\nT\u00e9l. : 06731 49 88 96<br>\nCourrier \u00e9lectronique : museum@alzey.de<br>\nInternet : <a href=\"http:\/\/www.museum-alzey.de\">www.museum-alzey.de<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Horaires d'ouverture :<br>\nDu lundi au vendredi de 10h \u00e0 12h30 et de 13h30 \u00e0 16h30<br>\nsam, dim et jours f\u00e9ri\u00e9s 10 \u00e0 12 et 14\n\u00e0 16.30 heures<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visites guid\u00e9es :<br>R\u00e9servable aupr\u00e8s de l'office de tourisme, t\u00e9l. : 06731 49 93 64 ; mail : <a href=\"mailto:touristinfo@alzey.de\">touristinfo@alzey.de<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>L'architecture moderne rencontre les tr\u00e9sors antiques. O\u00f9 cela se passe-t-il ? Dans le nouveau hall en pierre du mus\u00e9e d'Alzey. C'est l\u00e0 que sont expos\u00e9es les plus importantes d\u00e9couvertes romaines sur le sol allemand. Les pierres de temple et de cons\u00e9cration, les colonnes et les sculptures racontent une (des) histoire(s) qui, m\u00eame apr\u00e8s 2000 ans, reste(nt) passionnante(s). <\/p>","protected":false},"author":35,"featured_media":10065,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[320],"tags":[],"class_list":["post-10019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur-entdecken"],"acf":{"":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wo Steine Geschichte(n) erz\u00e4hlen - Rheinhessen-Blog<\/title>\n<meta name=\"description\" content=\"Moderne Architektur trifft auf antike Sch\u00e4tze. Wo? In der neuen Steinhalle des Alzeyer Museums. Dort sind mit die bedeutendsten r\u00f6mischen Funde auf deutschem Boden zu sehen. Die Tempel- und Weihesteine, S\u00e4ulen und Skulpturen erz\u00e4hlen Geschichte(n), die auch nach 2000 Jahren noch spannend sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rheinhessenblog.de\/fr\/ou-les-pierres-racontent-des-histoires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wo Steine Geschichte(n) erz\u00e4hlen - Rheinhessen-Blog\" \/>\n<meta property=\"og:description\" content=\"Moderne Architektur trifft auf antike Sch\u00e4tze. Wo? In der neuen Steinhalle des Alzeyer Museums. Dort sind mit die bedeutendsten r\u00f6mischen Funde auf deutschem Boden zu sehen. Die Tempel- und Weihesteine, S\u00e4ulen und Skulpturen erz\u00e4hlen Geschichte(n), die auch nach 2000 Jahren noch spannend sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rheinhessenblog.de\/fr\/ou-les-pierres-racontent-des-histoires\/\" \/>\n<meta property=\"og:site_name\" content=\"Rheinhessen-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-17T10:37:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T07:53:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Ehlke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Ehlke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/\"},\"author\":{\"name\":\"Thomas Ehlke\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/person\\\/4144f649f7564462e9fee7212a85ebc8\"},\"headline\":\"Wo Steine Geschichte(n) erz\u00e4hlen\",\"datePublished\":\"2023-03-17T10:37:50+00:00\",\"dateModified\":\"2023-10-17T07:53:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/\"},\"wordCount\":1853,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Jupitersaeule-Giganten-1-1-scaled-1.jpg\",\"articleSection\":[\"Kultur entdecken\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/\",\"name\":\"Wo Steine Geschichte(n) erz\u00e4hlen - Rheinhessen-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Jupitersaeule-Giganten-1-1-scaled-1.jpg\",\"datePublished\":\"2023-03-17T10:37:50+00:00\",\"dateModified\":\"2023-10-17T07:53:01+00:00\",\"description\":\"Moderne Architektur trifft auf antike Sch\u00e4tze. Wo? In der neuen Steinhalle des Alzeyer Museums. Dort sind mit die bedeutendsten r\u00f6mischen Funde auf deutschem Boden zu sehen. Die Tempel- und Weihesteine, S\u00e4ulen und Skulpturen erz\u00e4hlen Geschichte(n), die auch nach 2000 Jahren noch spannend sind.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Jupitersaeule-Giganten-1-1-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Jupitersaeule-Giganten-1-1-scaled-1.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/wo-steine-geschichten-erzaehlen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rheinhessenblog.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wo Steine Geschichte(n) erz\u00e4hlen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"name\":\"Rheinhessen-Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rheinhessenblog.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\",\"name\":\"Rheinhessen-Blog\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"width\":85,\"height\":26,\"caption\":\"Rheinhessen-Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/person\\\/4144f649f7564462e9fee7212a85ebc8\",\"name\":\"Thomas Ehlke\",\"description\":\"Geboren in Mainz, aufgewachsen in Oppenheim trage ich von Geburt an das Rheinhessen-Gen in mir. Als Redakteur der Allgemeinen Zeitung und Buchautor habe ich das Geschehen im Land der 1000 H\u00fcgel intensiv begleitet. Meine besondere Aufmerksamkeit gilt dem Wein, dem ich mich unter anderem als Host des VRM-Podcasts \u201eWein x 1\u201c widme. Foto: Sascha Kopp\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/fr\\\/author\\\/t-ehlke\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les pierres racontent l'histoire - Rheinhessen-Blog","description":"L'architecture moderne rencontre les tr\u00e9sors antiques. O\u00f9 cela se passe-t-il ? Dans le nouveau hall en pierre du mus\u00e9e d'Alzey. C'est l\u00e0 que sont expos\u00e9es les plus importantes d\u00e9couvertes romaines sur le sol allemand. Les pierres de temple et de cons\u00e9cration, les colonnes et les sculptures racontent une (des) histoire(s) qui, m\u00eame apr\u00e8s 2000 ans, reste(nt) passionnante(s).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rheinhessenblog.de\/fr\/ou-les-pierres-racontent-des-histoires\/","og_locale":"fr_FR","og_type":"article","og_title":"Wo Steine Geschichte(n) erz\u00e4hlen - Rheinhessen-Blog","og_description":"Moderne Architektur trifft auf antike Sch\u00e4tze. Wo? In der neuen Steinhalle des Alzeyer Museums. Dort sind mit die bedeutendsten r\u00f6mischen Funde auf deutschem Boden zu sehen. Die Tempel- und Weihesteine, S\u00e4ulen und Skulpturen erz\u00e4hlen Geschichte(n), die auch nach 2000 Jahren noch spannend sind.","og_url":"https:\/\/rheinhessenblog.de\/fr\/ou-les-pierres-racontent-des-histoires\/","og_site_name":"Rheinhessen-Blog","article_published_time":"2023-03-17T10:37:50+00:00","article_modified_time":"2023-10-17T07:53:01+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1.jpg","type":"image\/jpeg"}],"author":"Thomas Ehlke","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Thomas Ehlke","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/#article","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/"},"author":{"name":"Thomas Ehlke","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/person\/4144f649f7564462e9fee7212a85ebc8"},"headline":"Wo Steine Geschichte(n) erz\u00e4hlen","datePublished":"2023-03-17T10:37:50+00:00","dateModified":"2023-10-17T07:53:01+00:00","mainEntityOfPage":{"@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/"},"wordCount":1853,"commentCount":0,"publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"image":{"@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1.jpg","articleSection":["Kultur entdecken"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/","url":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/","name":"Les pierres racontent l'histoire - Rheinhessen-Blog","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/#primaryimage"},"image":{"@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1.jpg","datePublished":"2023-03-17T10:37:50+00:00","dateModified":"2023-10-17T07:53:01+00:00","description":"L'architecture moderne rencontre les tr\u00e9sors antiques. O\u00f9 cela se passe-t-il ? Dans le nouveau hall en pierre du mus\u00e9e d'Alzey. C'est l\u00e0 que sont expos\u00e9es les plus importantes d\u00e9couvertes romaines sur le sol allemand. Les pierres de temple et de cons\u00e9cration, les colonnes et les sculptures racontent une (des) histoire(s) qui, m\u00eame apr\u00e8s 2000 ans, reste(nt) passionnante(s).","breadcrumb":{"@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/#primaryimage","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1.jpg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/03\/Jupitersaeule-Giganten-1-1-scaled-1.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/rheinhessenblog.de\/wo-steine-geschichten-erzaehlen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rheinhessenblog.de\/"},{"@type":"ListItem","position":2,"name":"Wo Steine Geschichte(n) erz\u00e4hlen"}]},{"@type":"WebSite","@id":"https:\/\/rheinhessenblog.de\/#website","url":"https:\/\/rheinhessenblog.de\/","name":"Blog de la Hesse rh\u00e9nane","description":"","publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rheinhessenblog.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rheinhessenblog.de\/#organization","name":"Blog de la Hesse rh\u00e9nane","url":"https:\/\/rheinhessenblog.de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","width":85,"height":26,"caption":"Rheinhessen-Blog"},"image":{"@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/person\/4144f649f7564462e9fee7212a85ebc8","name":"Thomas Ehlke","description":"N\u00e9 \u00e0 Mayence, j'ai grandi \u00e0 Oppenheim et je porte en moi depuis ma naissance le g\u00e8ne de la Hesse rh\u00e9nane. En tant que r\u00e9dacteur de l'Allgemeine Zeitung et auteur de livres, j'ai suivi de pr\u00e8s les \u00e9v\u00e9nements du pays des 1000 collines. Je porte une attention particuli\u00e8re au vin, auquel je me consacre entre autres en tant qu'h\u00f4te du podcast VRM \u201eWein x 1\u201c. Photo : Sascha Kopp","url":"https:\/\/rheinhessenblog.de\/fr\/author\/t-ehlke\/"}]}},"_links":{"self":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/10019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/comments?post=10019"}],"version-history":[{"count":3,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/10019\/revisions"}],"predecessor-version":[{"id":13266,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/10019\/revisions\/13266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/media\/10065"}],"wp:attachment":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/media?parent=10019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/categories?post=10019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/tags?post=10019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}