{"id":7432,"date":"2021-11-17T16:25:00","date_gmt":"2021-11-17T15:25:00","guid":{"rendered":"http:\/\/blog.rheinhessen.de\/?p=7432"},"modified":"2023-10-25T16:42:49","modified_gmt":"2023-10-25T14:42:49","slug":"7-conseils-creatifs-pour-les-jours-de-pluie-en-rhenanie-hesse","status":"publish","type":"post","link":"https:\/\/rheinhessenblog.de\/fr\/7-kreative-tipps-fuer-rheinhessische-regentage\/","title":{"rendered":"7 conseils cr\u00e9atifs pour les jours de pluie en Hesse rh\u00e9nane"},"content":{"rendered":"<p class=\"wp-block-paragraph\"> - Nous avons sept conseils passionnants \u00e0 vous donner, que vous pouvez merveilleusement essayer lors des journ\u00e9es froides et humides en Hesse rh\u00e9nane. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Plein\nUne vue d'ensemble : VArea \u00e0 Mayence<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle aventure : depuis d\u00e9cembre 2017, vous pouvez vous rendre dans le quartier Weisenau de Mayence chez  <a href=\"https:\/\/varea.de\/home.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"VArea (s&#039;ouvre dans un nouvel onglet)\">VArea<\/a> vous plonger dans des mondes totalement nouveaux. Apr\u00e8s une br\u00e8ve introduction, on vous remettra vos lunettes VR et vous pourrez choisir parmi plus de quarante jeux ceux qui vous conviennent le mieux. Ici, on ne voit d\u00e9finitivement pas son environnement \u00e0 travers les sempiternelles lunettes roses. J'ai eu l'occasion de m'initier au monde virtuel et j'ai d\u00e9couvert le tir \u00e0 l'arc - un excellent passe-temps, et pas seulement les jours de pluie. Dans la VArea, vous pouvez jouer \u00e0 c\u0153ur joie sur plus de 600 m\u00e8tres carr\u00e9s : Soit ensemble, soit seul - les autres joueurs peuvent alors suivre le jeu via un \u00e9cran. Que ce soit une escape room, des montagnes russes ou une partie d'escalade virtuelle, la diversit\u00e9 est au rendez-vous. Mais il n'y a pas qu'avec les lunettes VR sur le nez que vous pouvez passer des heures divertissantes : Vous pouvez aussi jouer de mani\u00e8re plus classique au air hockey et au billard ou prouver vos comp\u00e9tences au baby-foot. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"7437\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/VArea-Mainz-Weisenau-klein-scaled-1-1024x768.jpg\" alt=\"Id\u00e9e d&#039;excursion en Hesse rh\u00e9nane VArea\" class=\"wp-image-7437\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/VArea-Mainz-Weisenau-klein-scaled-1-1024x768.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/VArea-Mainz-Weisenau-klein-scaled-1-300x225.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/VArea-Mainz-Weisenau-klein-scaled-1-768x576.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/VArea-Mainz-Weisenau-klein-scaled-1-1536x1152.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/VArea-Mainz-Weisenau-klein-scaled-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>D\u00e9tente\nTemps mort : Rheinhessen-Bad \u00e0 Nieder-Olm<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Qui n'a jamais r\u00eav\u00e9 de s'\u00e9vader un moment de la fr\u00e9n\u00e9sie du quotidien ? Et si on plongeait tout simplement ? Nulle part ailleurs, cela ne fonctionne aussi bien que dans une piscine. Le site<a href=\"https:\/\/www.rheinhessen.de\/a-rheinhessen-bad\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" Rheinhessen-Bad (s&#039;ouvre dans un nouvel onglet)\"> Hesse rh\u00e9nane-Bad<\/a> \u00e0 Nieder-Olm est l'un de mes pr\u00e9f\u00e9r\u00e9s dans la r\u00e9gion : l'installation bien entretenue offre de la place pour de nombreux baigneurs et marque des points avec un bassin pour non-nageurs, une installation \u00e0 tourbillons, un toboggan pour enfants ainsi qu'un bassin pour nageurs. Des chaises longues confortables vous invitent \u00e0 une pause reposante. Dans le grand bassin ext\u00e9rieur, vous pouvez en outre laisser le vent souffler autour de vous. Je pr\u00e9f\u00e8re g\u00e9n\u00e9ralement rester \u00e0 l'int\u00e9rieur ; j'y fais mes longueurs avec plaisir. Dans le Rheinhessen-Bad, on peut en outre transpirer \u00e0 grosses gouttes : Quatre saunas int\u00e9rieurs et deux saunas ext\u00e9rieurs permettent de s'\u00e9vader un peu du stress quotidien ; il suffit de laisser son esprit vagabonder ! Ensuite, vous pouvez vous restaurer au bistro. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"616\" data-id=\"7438\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Rheinhessen-Bad-Nieder-Olm-Rheinhessen-klein-scaled-1-1024x616.jpg\" alt=\"\" class=\"wp-image-7438\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Rheinhessen-Bad-Nieder-Olm-Rheinhessen-klein-scaled-1-1024x616.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Rheinhessen-Bad-Nieder-Olm-Rheinhessen-klein-scaled-1-300x180.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Rheinhessen-Bad-Nieder-Olm-Rheinhessen-klein-scaled-1-768x462.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Rheinhessen-Bad-Nieder-Olm-Rheinhessen-klein-scaled-1-1536x923.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Rheinhessen-Bad-Nieder-Olm-Rheinhessen-klein-scaled-1-2048x1231.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"861\" data-id=\"7439\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Nieder-Olm-Rheinhessen-Bad-Hallenbad-klein-scaled-1-1024x861.jpg\" alt=\"\" class=\"wp-image-7439\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Nieder-Olm-Rheinhessen-Bad-Hallenbad-klein-scaled-1-1024x861.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Nieder-Olm-Rheinhessen-Bad-Hallenbad-klein-scaled-1-300x252.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Nieder-Olm-Rheinhessen-Bad-Hallenbad-klein-scaled-1-768x646.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Nieder-Olm-Rheinhessen-Bad-Hallenbad-klein-scaled-1-1536x1291.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Nieder-Olm-Rheinhessen-Bad-Hallenbad-klein-scaled-1-2048x1722.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trinquer \u00e0 la vie : Vinoth\u00e8que de la cave des vignerons d'Ingelheim<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous aimez les vins de la Hesse rh\u00e9nane ? Le site <a href=\"https:\/\/www.rheinhessen.de\/ausgezeichnete-vinotheken\/a-vinothek-im-ingelheimer-winzerkeller\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Vinoth\u00e8que de la cave des vignerons (s&#039;ouvre dans un nouvel onglet)\">Vinoth\u00e8que dans la cave des vignerons<\/a> vous propose des vins fins provenant de 25 domaines viticoles et d'une distillerie de la r\u00e9gion d'Ingelheim. Il y a quelques semaines, l'entreprise a d'ailleurs \u00e9t\u00e9 r\u00e9compens\u00e9e par le DWI (Deutsches Weininstitut) : L'entreprise peut d\u00e9sormais compter parmi les 30 plus belles vinoth\u00e8ques d'Allemagne. Quels sont les c\u00e9pages les plus appr\u00e9ci\u00e9s dans la vinoth\u00e8que ? Les clients s'int\u00e9ressent surtout aux c\u00e9pages blancs et rouges de Bourgogne - apr\u00e8s tout, Ingelheim est aussi connue pour ces vins. La g\u00e9rante Cathrin Tronser appr\u00e9cie particuli\u00e8rement les c\u00e9pages pinot gris et sauvignon blanc et, pour les vins rouges, le pinot tardif et pr\u00e9coce. En bref, la vinoth\u00e8que de la cave des vignerons est un lieu pour tous ceux qui recherchent l'originalit\u00e9 et souhaitent d\u00e9guster des vins r\u00e9gionaux. Classe : vous pouvez \u00e9galement passer spontan\u00e9ment \u00e0 la vinoth\u00e8que pour une petite d\u00e9gustation - testez trois ou six vins. La carte de d\u00e9gustation comprend 25 vins au total, parmi lesquels vous pouvez choisir en fonction de vos go\u00fbts personnels. Dehors, la pluie cr\u00e9pite et vous d\u00e9gustez du jus de raisin dans la vinoth\u00e8que d'Ingelheim - on ne peut pas faire mieux, n'est-ce pas ? <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5507\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/10\/ingelheimer-winzerkeller-9-scaled-1-1024x683.jpg\" alt=\"Vinoth\u00e8ques et architecture : la vinoth\u00e8que moderne d&#039;Ingelheim\" class=\"wp-image-5507\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/10\/ingelheimer-winzerkeller-9-scaled-1-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/10\/ingelheimer-winzerkeller-9-scaled-1-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/10\/ingelheimer-winzerkeller-9-scaled-1-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/10\/ingelheimer-winzerkeller-9-scaled-1-1536x1024.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/10\/ingelheimer-winzerkeller-9-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Vinoth\u00e8ques Ingelheimer Winzerkeller<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pr\u00eat pour la sc\u00e8ne : Dinner\nfor One uff Rhoihessisch \u00e0 Oppenheim<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.restaurant-voelker.de\/dinner-for-one.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Dinner for One (s&#039;ouvre dans un nouvel onglet)\">D\u00eener pour un<\/a> - nous connaissons tous ce classique du Nouvel An. Ce qui me pla\u00eet le plus dans ce sketch, c'est qu'il soit jou\u00e9 dans mon dialecte, c'est-\u00e0-dire en rh\u00e9no-hessois. De telles repr\u00e9sentations ont r\u00e9guli\u00e8rement lieu dans une authentique cave vo\u00fbt\u00e9e du restaurant V\u00f6lker \u00e0 Oppenheim. J'ai d\u00e9j\u00e0 assist\u00e9 \u00e0 une repr\u00e9sentation il y a quelque temps et je peux donc vous la recommander vivement. Un programme vari\u00e9 et bien con\u00e7u vous attend : vous pouvez commencer la soir\u00e9e avec une ou deux coupes de champagne. Ensuite, le propri\u00e9taire Josef V\u00f6lker vous invitera \u00e0 une visite guid\u00e9e souterraine tr\u00e8s divertissante - un voyage passionnant dans le pass\u00e9. Plus tard, vous serez invit\u00e9s \u00e0 la f\u00eate d'anniversaire de Miss Sophie et assisterez \u00e0 la pi\u00e8ce amusante. Pas de panique : c'est bien s\u00fbr parfaitement compr\u00e9hensible m\u00eame pour ceux qui ne sont pas originaires de la Hesse rh\u00e9nane ! Un d\u00e9licieux repas de trois plats au restaurant vient finalement clore la soir\u00e9e. Aujourd'hui encore, je repense avec beaucoup de plaisir \u00e0 cet \u00e9v\u00e9nement divertissant. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"737\" data-id=\"7442\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Theaterstueck-Dinner-for-one-uff-rhoihessisch-klein-scaled-1-1024x737.jpg\" alt=\"\" class=\"wp-image-7442\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Theaterstueck-Dinner-for-one-uff-rhoihessisch-klein-scaled-1-1024x737.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Theaterstueck-Dinner-for-one-uff-rhoihessisch-klein-scaled-1-300x216.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Theaterstueck-Dinner-for-one-uff-rhoihessisch-klein-scaled-1-768x553.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Theaterstueck-Dinner-for-one-uff-rhoihessisch-klein-scaled-1-1536x1105.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Theaterstueck-Dinner-for-one-uff-rhoihessisch-klein-scaled-1-2048x1474.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">(c) Peter Pulkowski<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Inoubliable\nSoir\u00e9e : d\u00e9gustation de vin dans un tramway historique<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une d\u00e9gustation de vin est d\u00e9j\u00e0 une exp\u00e9rience formidable en soi - si en plus elle a lieu dans un lieu exceptionnel, la soir\u00e9e est quasiment programm\u00e9e. Anke Schneider et Gabriele Berges-Fehlinger de <em>Herrgottsgarten - Exp\u00e9riences vinicoles s\u00e9lectionn\u00e9es<\/em> proposent une multitude d'\u00e9v\u00e9nements extraordinaires. Mon pr\u00e9f\u00e9r\u00e9 est une passionnante balade nostalgique \u00e0 travers Mayence. En voiture, s'il vous pla\u00eet ! <a href=\"https:\/\/herrgottsgarten.de\/weinerlebnisse\/detail--weinprobe-in-der-nostalgischen-strassenbahn-in-mainz_458.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"La d\u00e9gustation de vin a lieu dans un tramway historique (s&#039;ouvre dans un nouvel onglet)\">La d\u00e9gustation de vin a lieu dans un tramway historique<\/a> de 1984 a eu lieu. Pendant le trajet, vous apprendrez des choses sur le th\u00e8me du vin et des histoires divertissantes sur Mayence qui ne manqueront pas de vous faire sourire. De plus, vous d\u00e9gusterez cinq vins et un secco provenant de domaines viticoles de la Hesse rh\u00e9nane ainsi que des petits d\u00e9lices de la r\u00e9gion. La sensation indescriptible de voyager dans un train nostalgique est offerte en prime : il traverse Mayence \u00e0 son propre rythme en s'\u00e9branlant doucement ; des souvenirs d'enfance sont r\u00e9veill\u00e9s. En bref : deux heures et demie de divertissement dont vous vous souviendrez certainement toujours avec plaisir. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"989\" height=\"768\" data-id=\"7443\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg\" alt=\"\" class=\"wp-image-7443\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg 989w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten-300x233.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten-768x596.jpg 768w\" sizes=\"(max-width: 989px) 100vw, 989px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Humoristique\nTemps mort : le th\u00e9\u00e2tre Gerry Jansen \u00e0 Alzey<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez passer des heures divertissantes, vous \u00eates au bon endroit \u00e0 Alzeyer <a href=\"http:\/\/www.gerryjansen.de\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Th\u00e9\u00e2tre Gerry Jansen (s&#039;ouvre dans un nouvel onglet)\">Th\u00e9\u00e2tre Gerry Jansen<\/a> Le charmant th\u00e9\u00e2tre de la Hellgasse existe depuis septembre 1995. La particularit\u00e9 : On n'y joue que des com\u00e9dies - car la vie \u00e9crit suffisamment de trag\u00e9dies, c'est bien connu ! Chaque fois, j'attends avec impatience le spectacle avec ma famille. <a href=\"https:\/\/www.rheinhessen.de\/e-gerry-jansen-theater-beste-freundinnen\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"pi\u00e8ce actuelle (s&#039;ouvre dans un nouvel onglet)\">pi\u00e8ce actuelle<\/a> de Gerry Jansen ; nous ne sommes jamais d\u00e9\u00e7us : d\u00e8s que nous prenons place sur les confortables si\u00e8ges rouges, que nous \u00e9coutons la musique joyeuse et que nous feuilletons une derni\u00e8re fois le petit programme, nous sommes impatients d'assister \u00e0 la repr\u00e9sentation. Le moment est enfin venu : le rideau s'ouvre. Les acteurs jouent avec passion leur \u0153uvre dr\u00f4le et nous font bien rire. Je vous conseille donc vivement d'y aller : Place aux com\u00e9dies qui mettent les muscles du rire \u00e0 rude \u00e9preuve ! Ou comme le dit Garry Jansen : Bienvenue sur la sc\u00e8ne professionnelle la plus folle d'Allemagne. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"7444\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Innenraum-Gerry-Jansen-Theater-Alezy-Rheinhessen-scaled-1-1024x768.jpg\" alt=\"\" class=\"wp-image-7444\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Innenraum-Gerry-Jansen-Theater-Alezy-Rheinhessen-scaled-1-1024x768.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Innenraum-Gerry-Jansen-Theater-Alezy-Rheinhessen-scaled-1-300x225.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Innenraum-Gerry-Jansen-Theater-Alezy-Rheinhessen-scaled-1-768x576.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Innenraum-Gerry-Jansen-Theater-Alezy-Rheinhessen-scaled-1-1536x1152.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Innenraum-Gerry-Jansen-Theater-Alezy-Rheinhessen-scaled-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Artistique\nPlaisir de la lecture : Vitraux de Chagall \u00e0 St. Stephan, Mayence <\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">C'est \u00e0 Mayence, et plus pr\u00e9cis\u00e9ment \u00e0 <a href=\"https:\/\/www.rheinhessen.de\/a-st-stephan\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"St. Stephan : (s&#039;ouvre dans un nouvel onglet)\">St. Stephan : <\/a>Vous pouvez y admirer des vitraux extr\u00eamement remarquables du c\u00e9l\u00e8bre peintre Marc Chagall. Comment en est-on arriv\u00e9 l\u00e0 ? Le cur\u00e9 de Saint-\u00c9tienne de l'\u00e9poque, Mgr Klaus Mayer, lui-m\u00eame grand amateur d'art, a \u00e9crit une lettre \u00e0 Chagall en 1973 pour lui demander un vitrail de sa conception. L'artiste, qui vit dans le sud de la France, a mis beaucoup de temps \u00e0 r\u00e9pondre. Mais il a finalement accept\u00e9 et neuf fen\u00eatres ont \u00e9t\u00e9 install\u00e9es, la premi\u00e8re en 1978. Mon conseil : participez comme moi \u00e0 l'une des visites guid\u00e9es int\u00e9ressantes et apprenez-en plus sur l'\u00e9glise du Stephansberg, l'artiste et ses vitraux extraordinaires. Mais vous pouvez aussi d\u00e9couvrir l'\u00e9glise par vous-m\u00eame : un guide audio-visuel num\u00e9rique, que vous pouvez emprunter sur place, vous fournira de pr\u00e9cieuses informations sur les vitraux de Chagall, le clo\u00eetre et d'autres curiosit\u00e9s de l'\u00e9glise. \u00c0 chaque visite, je savoure l'ambiance m\u00e9ditative et le silence qui r\u00e8gnent \u00e0 St. Stephan. C'est un \u00e9quilibre bienfaisant par rapport au monde souvent agit\u00e9. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"782\" data-id=\"7445\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/St-Stephan-Mainz-Chagall-Fenster-klein-scaled-1-1024x782.jpg\" alt=\"\" class=\"wp-image-7445\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/St-Stephan-Mainz-Chagall-Fenster-klein-scaled-1-1024x782.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/St-Stephan-Mainz-Chagall-Fenster-klein-scaled-1-300x229.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/St-Stephan-Mainz-Chagall-Fenster-klein-scaled-1-768x586.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/St-Stephan-Mainz-Chagall-Fenster-klein-scaled-1-1536x1172.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/St-Stephan-Mainz-Chagall-Fenster-klein-scaled-1-2048x1563.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ces autres<strong> <a rel=\"noreferrer noopener\" aria-label=\"Conseils pour les jours de pluie gris en Hesse rh\u00e9nane (s&#039;ouvre dans un nouvel onglet)\" href=\"https:\/\/rheinhessenblog.de\/fr\/rheinhessen-bei-regen-unsere-10-besten-schlechtwett\/\" target=\"_blank\">Conseils pour les jours de pluie gris en Hesse rh\u00e9nane<\/a><\/strong> ne laissent pas non plus de place \u00e0 l'ennui. <\/p>","protected":false},"excerpt":{"rendered":"<p>La Hesse rh\u00e9nane est connue pour \u00eatre une r\u00e9gion plut\u00f4t ensoleill\u00e9e. Mais ici aussi, il faut s'attendre \u00e0 des averses de temps en temps. Pas de quoi s'inqui\u00e9ter : vos vacances ne tomberont pas \u00e0 l'eau pour autant. -<\/p>","protected":false},"author":18,"featured_media":7443,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[320],"tags":[329,328,324],"class_list":["post-7432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur-entdecken","tag-familien","tag-sportliches","tag-weingenuss"],"acf":{"":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 kreative Tipps f\u00fcr rheinhessische Regentage - Rheinhessen-Blog<\/title>\n<meta name=\"description\" content=\"Rheinhessen ist bekanntlich eine eher sonnenverw\u00f6hnte Region. Aber auch hier muss man hin und wieder mit einem Schauer rechnen. Kein Grund zur Sorge: Euer Urlaub f\u00e4llt deswegen noch lange nicht ins Wasser. -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rheinhessenblog.de\/fr\/7-conseils-creatifs-pour-les-jours-de-pluie-en-rhenanie-hesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 kreative Tipps f\u00fcr rheinhessische Regentage - Rheinhessen-Blog\" \/>\n<meta property=\"og:description\" content=\"Rheinhessen ist bekanntlich eine eher sonnenverw\u00f6hnte Region. Aber auch hier muss man hin und wieder mit einem Schauer rechnen. Kein Grund zur Sorge: Euer Urlaub f\u00e4llt deswegen noch lange nicht ins Wasser. -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rheinhessenblog.de\/fr\/7-conseils-creatifs-pour-les-jours-de-pluie-en-rhenanie-hesse\/\" \/>\n<meta property=\"og:site_name\" content=\"Rheinhessen-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-17T15:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T14:42:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"989\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kristin Berschet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kristin Berschet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/\"},\"author\":{\"name\":\"Kristin Berschet\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/person\\\/7872c51979fef218e12fd16ed11f1930\"},\"headline\":\"7 kreative Tipps f\u00fcr rheinhessische Regentage\",\"datePublished\":\"2021-11-17T15:25:00+00:00\",\"dateModified\":\"2023-10-25T14:42:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/\"},\"wordCount\":1266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg\",\"keywords\":[\"Familien\",\"Sportliches\",\"Weingenuss\"],\"articleSection\":[\"Kultur entdecken\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/\",\"name\":\"7 kreative Tipps f\u00fcr rheinhessische Regentage - Rheinhessen-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg\",\"datePublished\":\"2021-11-17T15:25:00+00:00\",\"dateModified\":\"2023-10-25T14:42:49+00:00\",\"description\":\"Rheinhessen ist bekanntlich eine eher sonnenverw\u00f6hnte Region. Aber auch hier muss man hin und wieder mit einem Schauer rechnen. Kein Grund zur Sorge: Euer Urlaub f\u00e4llt deswegen noch lange nicht ins Wasser. -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg\",\"width\":989,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/7-kreative-tipps-fuer-rheinhessische-regentage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rheinhessenblog.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 kreative Tipps f\u00fcr rheinhessische Regentage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"name\":\"Rheinhessen-Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rheinhessenblog.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\",\"name\":\"Rheinhessen-Blog\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"width\":85,\"height\":26,\"caption\":\"Rheinhessen-Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/person\\\/7872c51979fef218e12fd16ed11f1930\",\"name\":\"Kristin Berschet\",\"description\":\"Als waschechtes Rheinhessen-M\u00e4dchen liebe ich meine Region \u00fcber alles. Ich mag die freundlichen Menschen, die abwechslungsreiche Natur und den guten Wein. Seit 2014 berichte ich auf meinem Blog Rheinhessenliebe vom sch\u00f6nsten Teil Deutschlands. Bild: Stephan Dinges\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/fr\\\/author\\\/heehler\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 conseils cr\u00e9atifs pour les jours de pluie en Hesse rh\u00e9nane - Rheinhessen-Blog","description":"La Hesse rh\u00e9nane est connue pour \u00eatre une r\u00e9gion plut\u00f4t ensoleill\u00e9e. Mais ici aussi, il faut s'attendre \u00e0 des averses de temps en temps. Pas de quoi s'inqui\u00e9ter : vos vacances ne tomberont pas \u00e0 l'eau pour autant. -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rheinhessenblog.de\/fr\/7-conseils-creatifs-pour-les-jours-de-pluie-en-rhenanie-hesse\/","og_locale":"fr_FR","og_type":"article","og_title":"7 kreative Tipps f\u00fcr rheinhessische Regentage - Rheinhessen-Blog","og_description":"Rheinhessen ist bekanntlich eine eher sonnenverw\u00f6hnte Region. Aber auch hier muss man hin und wieder mit einem Schauer rechnen. Kein Grund zur Sorge: Euer Urlaub f\u00e4llt deswegen noch lange nicht ins Wasser. -","og_url":"https:\/\/rheinhessenblog.de\/fr\/7-conseils-creatifs-pour-les-jours-de-pluie-en-rhenanie-hesse\/","og_site_name":"Rheinhessen-Blog","article_published_time":"2021-11-17T15:25:00+00:00","article_modified_time":"2023-10-25T14:42:49+00:00","og_image":[{"width":989,"height":768,"url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg","type":"image\/jpeg"}],"author":"Kristin Berschet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Kristin Berschet","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/#article","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/"},"author":{"name":"Kristin Berschet","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/person\/7872c51979fef218e12fd16ed11f1930"},"headline":"7 kreative Tipps f\u00fcr rheinhessische Regentage","datePublished":"2021-11-17T15:25:00+00:00","dateModified":"2023-10-25T14:42:49+00:00","mainEntityOfPage":{"@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/"},"wordCount":1266,"commentCount":0,"publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"image":{"@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg","keywords":["Familien","Sportliches","Weingenuss"],"articleSection":["Kultur entdecken"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/","url":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/","name":"7 conseils cr\u00e9atifs pour les jours de pluie en Hesse rh\u00e9nane - Rheinhessen-Blog","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/#primaryimage"},"image":{"@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg","datePublished":"2021-11-17T15:25:00+00:00","dateModified":"2023-10-25T14:42:49+00:00","description":"La Hesse rh\u00e9nane est connue pour \u00eatre une r\u00e9gion plut\u00f4t ensoleill\u00e9e. Mais ici aussi, il faut s'attendre \u00e0 des averses de temps en temps. Pas de quoi s'inqui\u00e9ter : vos vacances ne tomberont pas \u00e0 l'eau pour autant. -","breadcrumb":{"@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/#primaryimage","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2021\/11\/Historische-Strassenbahn-mit-Weinprobe-Mainz-Herrgottsgarten.jpg","width":989,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/rheinhessenblog.de\/7-kreative-tipps-fuer-rheinhessische-regentage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rheinhessenblog.de\/"},{"@type":"ListItem","position":2,"name":"7 kreative Tipps f\u00fcr rheinhessische Regentage"}]},{"@type":"WebSite","@id":"https:\/\/rheinhessenblog.de\/#website","url":"https:\/\/rheinhessenblog.de\/","name":"Blog de la Hesse rh\u00e9nane","description":"","publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rheinhessenblog.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rheinhessenblog.de\/#organization","name":"Blog de la Hesse rh\u00e9nane","url":"https:\/\/rheinhessenblog.de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","width":85,"height":26,"caption":"Rheinhessen-Blog"},"image":{"@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/person\/7872c51979fef218e12fd16ed11f1930","name":"Kristin Berschet","description":"En tant que vraie fille de la Hesse rh\u00e9nane, j'aime ma r\u00e9gion par-dessus tout. J'aime les gens sympathiques, la nature vari\u00e9e et le bon vin. Depuis 2014, je raconte la plus belle partie de l'Allemagne sur mon blog Rheinhessenliebe. Image : Stephan Dinges","url":"https:\/\/rheinhessenblog.de\/fr\/author\/heehler\/"}]}},"_links":{"self":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/7432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/comments?post=7432"}],"version-history":[{"count":6,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/7432\/revisions"}],"predecessor-version":[{"id":13410,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/7432\/revisions\/13410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/media\/7443"}],"wp:attachment":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/media?parent=7432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/categories?post=7432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/tags?post=7432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}