{"id":9524,"date":"2023-01-04T12:10:47","date_gmt":"2023-01-04T11:10:47","guid":{"rendered":"http:\/\/blog.rheinhessen.de\/?p=9524"},"modified":"2024-01-30T15:32:14","modified_gmt":"2024-01-30T14:32:14","slug":"salles-descalade-en-hesse-rhenane","status":"publish","type":"post","link":"https:\/\/rheinhessenblog.de\/fr\/kletter-boulderhallen-in-rheinhessen\/","title":{"rendered":"Salles d'escalade et de bloc en Hesse rh\u00e9nane"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Blockwerk salle d'escalade Mayence<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le site <a href=\"https:\/\/www.blockwerk.info\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\">Salle d'escalade Blockwerk<\/a> se trouve sur le terrain de l'ancienne usine de wagons \u00e0 Mayence-Mombach, entre les rues Am Sch\u00fctzenweg et Hauptstra\u00dfe. Elle porte le num\u00e9ro 6328 et se trouve \u00e0 quelques m\u00e8tres de la <a href=\"https:\/\/www.halle45.de\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\">Hall 45<\/a> de la ville. Ici, dans la grande et belle salle d'escalade au charme industriel, tout est plac\u00e9 sous le signe du bloc. Le Blockwerk vous propose une vaste offre avec de nombreuses voies pour les d\u00e9butants, les avanc\u00e9s et les professionnels. L'offre \u00e9tendue d'offres et de cours pour les enfants \u00e0 partir de 6 ans est particuli\u00e8rement attrayante. En outre, il y a un grand espace chillout pour se d\u00e9tendre avec des canap\u00e9s et des si\u00e8ges, un bistro et un bar pour les boissons et les petits snacks. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1.jpg\" alt=\"\" class=\"wp-image-9525\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1.jpg 960w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1-300x225.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-element-caption\"> \u00a9 Blockwerk Mayence <\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Salle de bloc Gravity \u00e0 Bad Kreuznach<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la <a href=\"https:\/\/www.gravity-kh.de\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\">Salle de bloc Gravity<\/a>  \u00e0 Bad Kreuznach, on prend de la hauteur sur 700 m\u00e8tres carr\u00e9s.  Diff\u00e9rents niveaux de difficult\u00e9 offrent, \u00e0 diff\u00e9rentes hauteurs, beaucoup de diversit\u00e9 et de sensations fortes pour toutes les classes d'\u00e2ge.  L'escalade de bloc dans une ambiance agr\u00e9able n'apporte pas seulement beaucoup de plaisir, mais influence aussi positivement votre forme et votre sant\u00e9.  Une vaste offre de cours pour les enfants, les adolescents et les adultes est tr\u00e8s demand\u00e9e. Le Gravity propose \u00e9galement des \u00e9v\u00e9nements sp\u00e9ciaux cr\u00e9atifs comme le programme de vacances pour les enfants, le bouldering in the dark ou le bouldering de la Saint-Nicolas. La boutique propose des sweats \u00e0 capuche et des d\u00e9bardeurs produits de mani\u00e8re durable.  Apr\u00e8s l'effort, direction le Caf\u00e9 Schwerkraft. Ici, tu peux facilement savourer ta passion pour le caf\u00e9 et remplir tes r\u00e9serves de glycog\u00e8ne avec de d\u00e9licieuses pizzas et tartes flamb\u00e9es faites maison. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Gravity2.jpg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">  \u00a9 Gravity Bad Kreuznach<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Hapik \u00e0 Mayence <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Hapik est une aventure d'escalade passionnante et pleine d'action \u00e0 Mayence. La particularit\u00e9 de cette activit\u00e9 : Dans le <a href=\"https:\/\/hapik.de\/standorte\/mainz\" target=\"_blank\" rel=\"noreferrer noopener\">Hapik<\/a> vous utilisez un syst\u00e8me d'assurage enti\u00e8rement automatique qui enroule automatiquement la corde pendant que vous grimpez et vous ram\u00e8ne en douceur au sol.  Pour vous, cela signifie que vous n'avez pas besoin d'une deuxi\u00e8me personne pour vous assurer et que vous pouvez commencer \u00e0 grimper imm\u00e9diatement. M\u00eame les plus petits ne peuvent pas se tromper et sont les bienvenus dans la salle d'escalade \u00e0 partir de 4 ans. Au total, 35 lignes d'escalade diff\u00e9rentes attendent tous les amateurs d'escalade.  De la montagne de spaghettis \u00e0 la liane de haricots en passant par l'astroball, il y en a pour tous les go\u00fbts. Ceux qui le souhaitent peuvent \u00e9galement se mesurer les uns aux autres sur le mur d'escalade. La salle d'escalade de Mainz-Hechtsheim est particuli\u00e8rement appr\u00e9ci\u00e9e pour les anniversaires d'enfants et les \u00e9v\u00e9nements de groupe. Pour reprendre des forces avant ou apr\u00e8s l'escalade, le bistro Ausguck offre une belle vue sur l'ensemble de l'ar\u00e8ne d'escalade.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Clip-and-Climb1-1024x682.jpg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">   Hapik Mayence <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>La Hesse rh\u00e9nane ne peut certes pas se targuer d'aventures grandioses en mati\u00e8re d'escalade dans les innombrables \u201ehiwwels\u201c, mais elle propose d\u00e9sormais, en plus des nombreuses et belles offres de randonn\u00e9es dans cette r\u00e9gion de d\u00e9couverte du vin, une offre petite mais raffin\u00e9e de salles d'escalade et de bloc. Cette offre fait le bonheur des d\u00e9butants comme des professionnels, qui peuvent y peaufiner leur technique et rester \u00e0 l'entra\u00eenement m\u00eame lorsqu'il pleut. <\/p>","protected":false},"author":4,"featured_media":9525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[321],"tags":[329,328],"class_list":["post-9524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wellness","tag-familien","tag-sportliches"],"acf":{"":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kletter &amp; Boulderhallen in Rheinhessen - Rheinhessen-Blog<\/title>\n<meta name=\"description\" content=\"Rheinhessen kann zwar nicht mit grandiosen Kletterabenteuern in den unz\u00e4hligen &quot;Hiwweln&quot; aufwarten, bietet aber neben den vielen sch\u00f6nen Wanderangeboten in der Weinerlebnisregion mittlerweile auch ein kleines aber feines Angebot an Kletter- und Boulderhallen. Das Angebot freut Anf\u00e4nger ebenso wie Profis, die hier an ihrer Technik feilen k\u00f6nnen und auch bei Regen im Training bleiben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rheinhessenblog.de\/fr\/salles-descalade-en-hesse-rhenane\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kletter &amp; Boulderhallen in Rheinhessen - Rheinhessen-Blog\" \/>\n<meta property=\"og:description\" content=\"Rheinhessen kann zwar nicht mit grandiosen Kletterabenteuern in den unz\u00e4hligen &quot;Hiwweln&quot; aufwarten, bietet aber neben den vielen sch\u00f6nen Wanderangeboten in der Weinerlebnisregion mittlerweile auch ein kleines aber feines Angebot an Kletter- und Boulderhallen. Das Angebot freut Anf\u00e4nger ebenso wie Profis, die hier an ihrer Technik feilen k\u00f6nnen und auch bei Regen im Training bleiben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rheinhessenblog.de\/fr\/salles-descalade-en-hesse-rhenane\/\" \/>\n<meta property=\"og:site_name\" content=\"Rheinhessen-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-04T11:10:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T14:32:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Halbig\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Halbig\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/\"},\"author\":{\"name\":\"Christian Halbig\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/person\\\/991bf250e4f4637b5db6809e8e3bb7de\"},\"headline\":\"Kletter &#038; Boulderhallen in Rheinhessen\",\"datePublished\":\"2023-01-04T11:10:47+00:00\",\"dateModified\":\"2024-01-30T14:32:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/\"},\"wordCount\":395,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Blockwerk1.jpg\",\"keywords\":[\"Familien\",\"Sportliches\"],\"articleSection\":[\"Wellness\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/\",\"name\":\"Kletter & Boulderhallen in Rheinhessen - Rheinhessen-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Blockwerk1.jpg\",\"datePublished\":\"2023-01-04T11:10:47+00:00\",\"dateModified\":\"2024-01-30T14:32:14+00:00\",\"description\":\"Rheinhessen kann zwar nicht mit grandiosen Kletterabenteuern in den unz\u00e4hligen \\\"Hiwweln\\\" aufwarten, bietet aber neben den vielen sch\u00f6nen Wanderangeboten in der Weinerlebnisregion mittlerweile auch ein kleines aber feines Angebot an Kletter- und Boulderhallen. Das Angebot freut Anf\u00e4nger ebenso wie Profis, die hier an ihrer Technik feilen k\u00f6nnen und auch bei Regen im Training bleiben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Blockwerk1.jpg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Blockwerk1.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/kletter-boulderhallen-in-rheinhessen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rheinhessenblog.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kletter &#038; Boulderhallen in Rheinhessen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"name\":\"Rheinhessen-Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rheinhessenblog.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\",\"name\":\"Rheinhessen-Blog\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"width\":85,\"height\":26,\"caption\":\"Rheinhessen-Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/person\\\/991bf250e4f4637b5db6809e8e3bb7de\",\"name\":\"Christian Halbig\",\"description\":\"Als geb\u00fcrtiger Mainzer, der sich als Rheinhesse f\u00fchlt, bin ich in meiner Freizeit viel in der Region unterwegs: Beim Wandern, Radfahren und diversen Ausfl\u00fcgen zu Weinevents oder Kulturveranstaltungen bin ich immer wieder auf der Suche nach neuen spannenden Angeboten und Pl\u00e4tzen.\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/fr\\\/author\\\/halbig\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salles d'escalade et de bloc en Hesse rh\u00e9nane - Blog Hesse rh\u00e9nane","description":"La Hesse rh\u00e9nane ne peut certes pas se targuer d'aventures grandioses en mati\u00e8re d'escalade dans les innombrables \"hiwwels\", mais elle propose d\u00e9sormais, en plus des nombreuses et belles offres de randonn\u00e9es dans cette r\u00e9gion de d\u00e9couverte du vin, une offre petite mais raffin\u00e9e de salles d'escalade et de bloc. Cette offre fait le bonheur des d\u00e9butants comme des professionnels, qui peuvent y peaufiner leur technique et rester \u00e0 l'entra\u00eenement m\u00eame lorsqu'il pleut.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rheinhessenblog.de\/fr\/salles-descalade-en-hesse-rhenane\/","og_locale":"fr_FR","og_type":"article","og_title":"Kletter & Boulderhallen in Rheinhessen - Rheinhessen-Blog","og_description":"Rheinhessen kann zwar nicht mit grandiosen Kletterabenteuern in den unz\u00e4hligen \"Hiwweln\" aufwarten, bietet aber neben den vielen sch\u00f6nen Wanderangeboten in der Weinerlebnisregion mittlerweile auch ein kleines aber feines Angebot an Kletter- und Boulderhallen. Das Angebot freut Anf\u00e4nger ebenso wie Profis, die hier an ihrer Technik feilen k\u00f6nnen und auch bei Regen im Training bleiben.","og_url":"https:\/\/rheinhessenblog.de\/fr\/salles-descalade-en-hesse-rhenane\/","og_site_name":"Rheinhessen-Blog","article_published_time":"2023-01-04T11:10:47+00:00","article_modified_time":"2024-01-30T14:32:14+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1.jpg","type":"image\/jpeg"}],"author":"Christian Halbig","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christian Halbig","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/#article","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/"},"author":{"name":"Christian Halbig","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/person\/991bf250e4f4637b5db6809e8e3bb7de"},"headline":"Kletter &#038; Boulderhallen in Rheinhessen","datePublished":"2023-01-04T11:10:47+00:00","dateModified":"2024-01-30T14:32:14+00:00","mainEntityOfPage":{"@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/"},"wordCount":395,"commentCount":0,"publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"image":{"@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1.jpg","keywords":["Familien","Sportliches"],"articleSection":["Wellness"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/","url":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/","name":"Salles d'escalade et de bloc en Hesse rh\u00e9nane - Blog Hesse rh\u00e9nane","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/#primaryimage"},"image":{"@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1.jpg","datePublished":"2023-01-04T11:10:47+00:00","dateModified":"2024-01-30T14:32:14+00:00","description":"La Hesse rh\u00e9nane ne peut certes pas se targuer d'aventures grandioses en mati\u00e8re d'escalade dans les innombrables \"hiwwels\", mais elle propose d\u00e9sormais, en plus des nombreuses et belles offres de randonn\u00e9es dans cette r\u00e9gion de d\u00e9couverte du vin, une offre petite mais raffin\u00e9e de salles d'escalade et de bloc. Cette offre fait le bonheur des d\u00e9butants comme des professionnels, qui peuvent y peaufiner leur technique et rester \u00e0 l'entra\u00eenement m\u00eame lorsqu'il pleut.","breadcrumb":{"@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/#primaryimage","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1.jpg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2022\/11\/Blockwerk1.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/rheinhessenblog.de\/kletter-boulderhallen-in-rheinhessen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rheinhessenblog.de\/"},{"@type":"ListItem","position":2,"name":"Kletter &#038; Boulderhallen in Rheinhessen"}]},{"@type":"WebSite","@id":"https:\/\/rheinhessenblog.de\/#website","url":"https:\/\/rheinhessenblog.de\/","name":"Blog de la Hesse rh\u00e9nane","description":"","publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rheinhessenblog.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rheinhessenblog.de\/#organization","name":"Blog de la Hesse rh\u00e9nane","url":"https:\/\/rheinhessenblog.de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","width":85,"height":26,"caption":"Rheinhessen-Blog"},"image":{"@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/person\/991bf250e4f4637b5db6809e8e3bb7de","name":"Christian Halbig","description":"Originaire de Mayence, je me sens Hesse rh\u00e9nane et passe beaucoup de temps libre dans la r\u00e9gion : en me promenant \u00e0 pied ou \u00e0 v\u00e9lo et en faisant diverses excursions pour assister \u00e0 des \u00e9v\u00e9nements viticoles ou culturels, je suis toujours \u00e0 la recherche de nouvelles offres et de nouveaux lieux passionnants.","url":"https:\/\/rheinhessenblog.de\/fr\/author\/halbig\/"}]}},"_links":{"self":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/9524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/comments?post=9524"}],"version-history":[{"count":7,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/9524\/revisions"}],"predecessor-version":[{"id":13930,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/posts\/9524\/revisions\/13930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/media\/9525"}],"wp:attachment":[{"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/media?parent=9524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/categories?post=9524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rheinhessenblog.de\/fr\/wp-json\/wp\/v2\/tags?post=9524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}