{"id":5303,"date":"2020-12-02T17:01:37","date_gmt":"2020-12-02T16:01:37","guid":{"rendered":"http:\/\/blog.rheinhessen.de\/?p=5303"},"modified":"2025-10-31T14:26:13","modified_gmt":"2025-10-31T13:26:13","slug":"levende-geschiedenis-met-johannes-gutenberg-tijdens-een-persoonlijke-rondleiding-door-mainz","status":"publish","type":"post","link":"https:\/\/rheinhessenblog.de\/nl\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/","title":{"rendered":"Levende geschiedenis: met Johannes Gutenberg zelf door Mainz"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-titelbild-1-scaled-1-1024x683.jpg\" alt=\"\" class=\"wp-image-5313\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-titelbild-1-scaled-1-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-titelbild-1-scaled-1-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-titelbild-1-scaled-1-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-titelbild-1-scaled-1-1536x1024.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-titelbild-1-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Elmar Rettinger is sinds 1980 gids in de stad Mainz. Sinds tien jaar geeft hij rondleidingen in Gutenbergkostuum om de geschiedenis op een levendige manier over te brengen. Ik ontmoette hem en vroeg hem wat hem aantrekt in de historische figuur, hoe hij zich voelt in kostuum en wat de werkplek van zijn alter ego zo charmant maakt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Afgestemd op het lichaam<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Op weg naar mijn ontmoeting met \"Johannes Gutenberg\" kom ik het volgende tegen <a rel=\"noreferrer noopener\" aria-label=\"de grootste zoon van de stad Mainz (opent in nieuw tabblad)\" href=\"https:\/\/www.rheinhessen.de\/gutenberg\" target=\"_blank\">de grootste zoon van de stad Mainz<\/a> al in de vorm van zijn meer dan levensgrote monument op de Gutenbergplatz. Hij waakt majestueus over de levendige drukte aan zijn voeten. Ik wandel langs het imposante <a rel=\"noreferrer noopener\" aria-label=\"Keizerlijke kathedraal (opent in nieuw tabblad)\" href=\"https:\/\/www.rheinhessen.de\/mainzer-dom-2\" target=\"_blank\">Keizerlijke Kathedraal <\/a>langs in de richting van het Gutenberg Museum, waar de hele wereld van drukkunst, boeken en schrijven op me wacht. Net als een spannend gesprek met historicus en rondleider Elmar Rettinger.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-denkmal-scaled-1-683x1024.jpg\" alt=\"\" class=\"wp-image-5305\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-denkmal-scaled-1-683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-denkmal-scaled-1-200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-denkmal-scaled-1-768x1152.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-denkmal-scaled-1-1024x1536.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-denkmal-scaled-1-1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-denkmal-scaled-1.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sinds een jaar of tien belichaamt hij de man die in de 15e eeuw een revolutie teweegbracht in de conventionele, ingewikkelde methoden van boekproductie met een beweegbare letter, een drukpers en wat drukinkt. En daarmee de overdracht van kennis en de toegang tot onderwijs democratiseerde. Voor mijn gesprekspartner is zijn <a rel=\"noreferrer noopener\" aria-label=\" (opent in nieuw tabblad)\" href=\"https:\/\/www.mainz-tourismus.com\/stadtfuehrungen\/oeffentliche-stadtfuehrungen\/allgemeines-angebot\/kostuemfuehrungen\/\" target=\"_blank\">Kostuum tour<\/a> als Gutenberg een geweldige manier om deze geschiedenis zo levendig en levendig mogelijk over te brengen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-fuehrung-scaled-1-683x1024.jpg\" alt=\"\" class=\"wp-image-5306\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-fuehrung-scaled-1-683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-fuehrung-scaled-1-200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-fuehrung-scaled-1-768x1152.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-fuehrung-scaled-1-1024x1536.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-fuehrung-scaled-1-1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-fuehrung-scaled-1.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Elmar Rettinger onthult dat hij aanvankelijk bij toeval in de rol van boekdrukker was geslopen. In het kader van een wetenschappelijk project werd kleding gemaakt die typisch was voor de 15e eeuw en hij mocht zich voordoen als de projectleider. Pas daarna kwam hij op het briljante idee: \"Een kostuum trekt speciale aandacht en zo kwam ik op het idee om dit te implementeren in mijn rondleidingen voor gasten.\"<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fluweel en zijde<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Authenticiteit is vooral belangrijk voor de historicus. \"Je moet voorzichtig zijn als je zo'n kostuum maakt,\" vertelt de gids. Van tevoren had hij uitgebreid onderzocht hoe patrici\u00ebrs zich vroeger kleedden, want Johannes Gutenberg was zo'n patrici\u00ebr. Hoogwaardige materialen zoals natuurzijde en zwaar fluweel, pofmouwen met \"vreemde splitten\" en opvallende snavelschoenen maken allemaal deel uit van zijn ensemble. \"Iedereen vindt vooral de schoenen erg chic,\" merkt hij geamuseerd op.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-lettern-scaled-1-683x1024.jpg\" alt=\"\" class=\"wp-image-5307\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-lettern-scaled-1-683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-lettern-scaled-1-200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-lettern-scaled-1-768x1152.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-lettern-scaled-1-1024x1536.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-lettern-scaled-1-1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-lettern-scaled-1.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ik merk al snel dat Elmar Rettinger de gave heeft om geconcentreerde historische kennis in spannende feiten te verpakken. Bijvoorbeeld als hij het heeft over de gedempte kleuren van zijn gewaden. Opvallende kleding was uitsluitend voorbehouden aan de adel en paars aan de geestelijkheid. Natuurlijk draagt hij geen horloge tijdens zijn stadsrondleidingen, het moet tenslotte authentiek zijn. \"Als de gasten ge\u00efnteresseerd zijn en vragen stellen, dan kijk je niet eens op je horloge. Dan is het gewoon leuk om ze iets te vertellen,\" zegt hij.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-druckerpresse-scaled-1-683x1024.jpg\" alt=\"\" class=\"wp-image-5308\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-druckerpresse-scaled-1-683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-druckerpresse-scaled-1-200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-druckerpresse-scaled-1-768x1152.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-druckerpresse-scaled-1-1024x1536.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-druckerpresse-scaled-1-1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-druckerpresse-scaled-1.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Over de kersenboomgaard en kersen eten<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En hij vertelt graag: \"Ik wil informatie over de tijd van toen. Wie was de baas in de stad, hoe waren de sociale omstandigheden en waarom had Mainz zoveel schulden?\" Natuurlijk draaien zijn rondleidingen ook om het leven en werk van Johannes Gutenberg zelf. Elmar Rettinger neemt zijn groepen mee naar alle plaatsen die met hem in verband worden gebracht. Hij begint hier in het Gutenberg Museum - natuurlijk met een demonstratie van de drukpers - en leidt vervolgens de hele oude stad door.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-museum-scaled-1-1024x683.jpg\" alt=\"\" class=\"wp-image-5309\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-museum-scaled-1-1024x683.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-museum-scaled-1-300x200.jpg 300w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-museum-scaled-1-768x512.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-museum-scaled-1-1536x1024.jpg 1536w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-museum-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Zowel professioneel als priv\u00e9 is de reisleider vooral dol op de pleinen van Mainz. En de oude handelsstad heeft er veel. Of het nu gaat om de vier levendige Dompleinen, de centrale Schillerplatz of de prachtige Kirschgarten met zijn historische vakwerkhuizen, waarvan sommige bewaard zijn gebleven uit de tijd van Gutenberg. \"Het zijn de pleinen in Mainz die deze stad zo charmant maken,\" vertelt Elmar Rettinger enthousiast.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1-683x1024.jpg\" alt=\"Gutenberg\" class=\"wp-image-5310\" srcset=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1-683x1024.jpg 683w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1-200x300.jpg 200w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1-768x1152.jpg 768w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1-1024x1536.jpg 1024w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1-1366x2048.jpg 1366w, https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tijdens ons gesprek over Johannes Gutenberg vervalt hij herhaaldelijk in de eerste persoon. Hij moet lachen als hij dit opmerkt en verzekert me dat hij nu al weet dat hij niet de echte is: \"Ik ben een heel rustige jongen en Johannes Gutenberg was waarschijnlijk een heel opvliegend persoon, heel anders.\" Hij zegt dat er heel weinig over hem bekend is, en dat weinige komt voornamelijk uit rechtbankverslagen. \"Hij was helemaal niet makkelijk in de omgang en misschien is dat wel wat mij aantrekt in de rol,\" geeft de gids toe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>De dubbele Gutenberg<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Maar de gekostumeerde Elmar Rettinger wordt nooit boos zoals zijn alter ego, omdat hij zich eigenlijk niet zo anders voelt in de zware jas. Het is geen enkel probleem om in Mainz een kostuum te dragen, merkt hij schouderophalend op. Integendeel: \"De mensen van Mainz zijn de meest <a rel=\"noreferrer noopener\" aria-label=\"Vastenavond (opent in nieuw tabblad)\" href=\"https:\/\/www.rheinhessen.de\/mainzer-fastnacht\" target=\"_blank\">Vastenavond<\/a> hier gewend. Keer op keer is hij zelfs blij met warme begroetingen en grote, verbaasde kinderogen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De deelnemers van twee groepen waren zeker verbaasd toen ze op een mooie dag ineens dubbel zagen. De reisleider moest lachen toen hij zijn favoriete anekdote vertelde. Een collega heeft ook een kostuum en op die dag kwamen twee Johannes Gutenbergs elkaar toevallig tegen. Hij pauzeert even. Misschien moet hij er eens over nadenken om naar Straatsburg te gaan, want daar heeft de drukker een paar jaar gewoond. Maar hij schudt snel zijn hoofd: \"Daar hebben ze waarschijnlijk al hun eigen Gutenberg. Dus Elmar Rettinger zal nog lang in Mainz blijven!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Je Gutenbergkostuumtour door Mainz<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Naast de spannende Gutenbergkostuumtour, die je kunt vinden op <a href=\"https:\/\/www.mainz-tourismus.com\/stadtfuehrungen\/gruppenfuehrungen\/kostuemfuehrungen\" target=\"_blank\" rel=\"noreferrer noopener\">deze pagina<\/a> Elmar Rettinger behandelt ook veel van de <a aria-label=\"meer stadstours (opent in nieuw tabblad)\" href=\"https:\/\/www.mainz-tourismus.com\/stadtfuehrungen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Meer rondleidingen door de stad<\/a> van de Romeinse tijd via het nationaalsocialistische tijdperk naar het heden. Na een ontmoeting met de charismatische historicus en gids weet ik zeker dat elk bezoek een levendige ervaring is.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Johannes Gutenberg, de uitvinder van de moderne boekdrukkunst, is een echte inwoner van Mainz. In de hoofdstad van Rijnland-Palts kun je in zijn voetsporen treden - en zelfs samen met hem!<\/p>","protected":false},"author":26,"featured_media":5310,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[320],"tags":[],"class_list":["post-5303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur-entdecken"],"acf":{"":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lebendige Geschichte: Mit Johannes Gutenberg h\u00f6chstpers\u00f6nlich durch Mainz - Rheinhessen-Blog<\/title>\n<meta name=\"description\" content=\"Johannes Gutenberg, der Erfinder des modernen Buchdrucks, ist ein waschechter Mainzer. In der Landeshauptstadt von Rheinland-Pfalz k\u00f6nnt Ihr auf seinen Spuren wandeln \u2013 und das sogar mit ihm gemeinsam!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rheinhessenblog.de\/nl\/levende-geschiedenis-met-johannes-gutenberg-tijdens-een-persoonlijke-rondleiding-door-mainz\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lebendige Geschichte: Mit Johannes Gutenberg h\u00f6chstpers\u00f6nlich durch Mainz - Rheinhessen-Blog\" \/>\n<meta property=\"og:description\" content=\"Johannes Gutenberg, der Erfinder des modernen Buchdrucks, ist ein waschechter Mainzer. In der Landeshauptstadt von Rheinland-Pfalz k\u00f6nnt Ihr auf seinen Spuren wandeln \u2013 und das sogar mit ihm gemeinsam!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rheinhessenblog.de\/nl\/levende-geschiedenis-met-johannes-gutenberg-tijdens-een-persoonlijke-rondleiding-door-mainz\/\" \/>\n<meta property=\"og:site_name\" content=\"Rheinhessen-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T16:01:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T13:26:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalie Teschauer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalie Teschauer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/\"},\"author\":{\"name\":\"Natalie Teschauer\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/person\\\/1be824f14844c580508225f586044717\"},\"headline\":\"Lebendige Geschichte: Mit Johannes Gutenberg h\u00f6chstpers\u00f6nlich durch Mainz\",\"datePublished\":\"2020-12-02T16:01:37+00:00\",\"dateModified\":\"2025-10-31T13:26:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/\"},\"wordCount\":960,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/mainz-gutenberg-kirschgarten-scaled-1.jpg\",\"articleSection\":[\"Kultur entdecken\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/\",\"name\":\"Lebendige Geschichte: Mit Johannes Gutenberg h\u00f6chstpers\u00f6nlich durch Mainz - Rheinhessen-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/mainz-gutenberg-kirschgarten-scaled-1.jpg\",\"datePublished\":\"2020-12-02T16:01:37+00:00\",\"dateModified\":\"2025-10-31T13:26:13+00:00\",\"description\":\"Johannes Gutenberg, der Erfinder des modernen Buchdrucks, ist ein waschechter Mainzer. In der Landeshauptstadt von Rheinland-Pfalz k\u00f6nnt Ihr auf seinen Spuren wandeln \u2013 und das sogar mit ihm gemeinsam!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/mainz-gutenberg-kirschgarten-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/mainz-gutenberg-kirschgarten-scaled-1.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"Gutenberg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rheinhessenblog.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lebendige Geschichte: Mit Johannes Gutenberg h\u00f6chstpers\u00f6nlich durch Mainz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"name\":\"Rheinhessen-Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rheinhessenblog.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\",\"name\":\"Rheinhessen-Blog\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"width\":85,\"height\":26,\"caption\":\"Rheinhessen-Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/person\\\/1be824f14844c580508225f586044717\",\"name\":\"Natalie Teschauer\",\"description\":\"Als externe Autorin f\u00fcr den Rheinhessen-Blog nehme ich Euch gerne mit auf meine Entdeckungstouren durch Rheinhessen. Mit Kamera und Notizbuch immer im Gep\u00e4ck, erkunde ich die Region der tausend Hiwwel, lerne die Vielfalt des Weins kennen und treffe gastfreundliche Rheinhessen.\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/nl\\\/author\\\/teschauer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Levende geschiedenis: Met Johannes Gutenberg zelf door Mainz - Rheinhessen-Blog","description":"Johannes Gutenberg, de uitvinder van de moderne boekdrukkunst, is een echte inwoner van Mainz. In de hoofdstad van Rijnland-Palts kun je in zijn voetsporen treden - en zelfs samen met hem!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rheinhessenblog.de\/nl\/levende-geschiedenis-met-johannes-gutenberg-tijdens-een-persoonlijke-rondleiding-door-mainz\/","og_locale":"nl_NL","og_type":"article","og_title":"Lebendige Geschichte: Mit Johannes Gutenberg h\u00f6chstpers\u00f6nlich durch Mainz - Rheinhessen-Blog","og_description":"Johannes Gutenberg, der Erfinder des modernen Buchdrucks, ist ein waschechter Mainzer. In der Landeshauptstadt von Rheinland-Pfalz k\u00f6nnt Ihr auf seinen Spuren wandeln \u2013 und das sogar mit ihm gemeinsam!","og_url":"https:\/\/rheinhessenblog.de\/nl\/levende-geschiedenis-met-johannes-gutenberg-tijdens-een-persoonlijke-rondleiding-door-mainz\/","og_site_name":"Rheinhessen-Blog","article_published_time":"2020-12-02T16:01:37+00:00","article_modified_time":"2025-10-31T13:26:13+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1.jpg","type":"image\/jpeg"}],"author":"Natalie Teschauer","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Natalie Teschauer","Geschatte leestijd":"7 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/#article","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/"},"author":{"name":"Natalie Teschauer","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/person\/1be824f14844c580508225f586044717"},"headline":"Lebendige Geschichte: Mit Johannes Gutenberg h\u00f6chstpers\u00f6nlich durch Mainz","datePublished":"2020-12-02T16:01:37+00:00","dateModified":"2025-10-31T13:26:13+00:00","mainEntityOfPage":{"@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/"},"wordCount":960,"commentCount":0,"publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"image":{"@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1.jpg","articleSection":["Kultur entdecken"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/","url":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/","name":"Levende geschiedenis: Met Johannes Gutenberg zelf door Mainz - Rheinhessen-Blog","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/#primaryimage"},"image":{"@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1.jpg","datePublished":"2020-12-02T16:01:37+00:00","dateModified":"2025-10-31T13:26:13+00:00","description":"Johannes Gutenberg, de uitvinder van de moderne boekdrukkunst, is een echte inwoner van Mainz. In de hoofdstad van Rijnland-Palts kun je in zijn voetsporen treden - en zelfs samen met hem!","breadcrumb":{"@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/#primaryimage","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1.jpg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2020\/08\/mainz-gutenberg-kirschgarten-scaled-1.jpg","width":1707,"height":2560,"caption":"Gutenberg"},{"@type":"BreadcrumbList","@id":"https:\/\/rheinhessenblog.de\/lebendige-geschichte-mit-johannes-gutenberg-hoechstpersoenlich-durch-mainz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rheinhessenblog.de\/"},{"@type":"ListItem","position":2,"name":"Lebendige Geschichte: Mit Johannes Gutenberg h\u00f6chstpers\u00f6nlich durch Mainz"}]},{"@type":"WebSite","@id":"https:\/\/rheinhessenblog.de\/#website","url":"https:\/\/rheinhessenblog.de\/","name":"Blog","description":"","publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rheinhessenblog.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/rheinhessenblog.de\/#organization","name":"Blog","url":"https:\/\/rheinhessenblog.de\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","width":85,"height":26,"caption":"Rheinhessen-Blog"},"image":{"@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/person\/1be824f14844c580508225f586044717","name":"Natalie Teschauer","description":"Als externe auteur voor de Rheinhessen blog neem ik je graag mee op mijn ontdekkingstochten door Rheinhessen. Met camera en notitieblok altijd in mijn bagage verken ik de regio van duizend Hiwwel, leer ik de diversiteit aan wijn kennen en ontmoet ik gastvrije Rheinhessenaren.","url":"https:\/\/rheinhessenblog.de\/nl\/author\/teschauer\/"}]}},"_links":{"self":[{"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/posts\/5303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/comments?post=5303"}],"version-history":[{"count":8,"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/posts\/5303\/revisions"}],"predecessor-version":[{"id":16983,"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/posts\/5303\/revisions\/16983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/media\/5310"}],"wp:attachment":[{"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/media?parent=5303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/categories?post=5303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/tags?post=5303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}