{"id":376,"count":1,"description":"","link":"https:\/\/rheinhessenblog.de\/nl\/schlagwort\/genuss\/","name":"Plezier","slug":"plezier","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Genuss Archive - Rheinhessen-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rheinhessenblog.de\/nl\/trefwoord\/plezier\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Genuss Archive - Rheinhessen-Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rheinhessenblog.de\/nl\/trefwoord\/plezier\/\" \/>\n<meta property=\"og:site_name\" content=\"Rheinhessen-Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/schlagwort\\\/genuss\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/schlagwort\\\/genuss\\\/\",\"name\":\"Genuss Archive - Rheinhessen-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/schlagwort\\\/genuss\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/schlagwort\\\/genuss\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rheinhessenblog.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Genuss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#website\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"name\":\"Rheinhessen-Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rheinhessenblog.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#organization\",\"name\":\"Rheinhessen-Blog\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"contentUrl\":\"https:\\\/\\\/rheinhessenblog.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Rheinhessenlogo.svg\",\"width\":85,\"height\":26,\"caption\":\"Rheinhessen-Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/rheinhessenblog.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Genuss Archive - Rheinhessen-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rheinhessenblog.de\/nl\/trefwoord\/plezier\/","og_locale":"nl_NL","og_type":"article","og_title":"Genuss Archive - Rheinhessen-Blog","og_url":"https:\/\/rheinhessenblog.de\/nl\/trefwoord\/plezier\/","og_site_name":"Rheinhessen-Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rheinhessenblog.de\/schlagwort\/genuss\/","url":"https:\/\/rheinhessenblog.de\/schlagwort\/genuss\/","name":"Verwennerij Archief - Rheinhessen-Blog","isPartOf":{"@id":"https:\/\/rheinhessenblog.de\/#website"},"breadcrumb":{"@id":"https:\/\/rheinhessenblog.de\/schlagwort\/genuss\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/rheinhessenblog.de\/schlagwort\/genuss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rheinhessenblog.de\/"},{"@type":"ListItem","position":2,"name":"Genuss"}]},{"@type":"WebSite","@id":"https:\/\/rheinhessenblog.de\/#website","url":"https:\/\/rheinhessenblog.de\/","name":"Blog","description":"","publisher":{"@id":"https:\/\/rheinhessenblog.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rheinhessenblog.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/rheinhessenblog.de\/#organization","name":"Blog","url":"https:\/\/rheinhessenblog.de\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/","url":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","contentUrl":"https:\/\/rheinhessenblog.de\/wp-content\/uploads\/2023\/07\/Rheinhessenlogo.svg","width":85,"height":26,"caption":"Rheinhessen-Blog"},"image":{"@id":"https:\/\/rheinhessenblog.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/tags\/376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rheinhessenblog.de\/nl\/wp-json\/wp\/v2\/posts?tags=376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}